{"id":1000061,"date":"2008-11-30T00:00:00","date_gmt":"2008-11-29T23:00:00","guid":{"rendered":""},"modified":"2019-04-29T16:53:25","modified_gmt":"2019-04-29T14:53:25","slug":"pillola-contraccettiva-minulet","status":"publish","type":"post","link":"https:\/\/www.comodo.it\/blog\/pillola-contraccettiva-minulet\/","title":{"rendered":"Pillola Contraccettiva Minulet"},"content":{"rendered":"<p>WYETHLEDERLE SpA<br \/>\n<strong>PRINCIPIO ATTIVO:<\/strong><br \/>\nGestodene 0,075 mg; etinilestradiolo 0,03 mg.<br \/>\n<strong>ECCIPIENTI:<\/strong><br \/>\nLattosio, amido di mais, polivinilpirrolidone 25.000, sodio calcio edetato, magnesiostearato, saccarosio, polivinilpirrolidone 700.000, polietilenglicole 6000, calcio carbonato, talco, estere etilenglicolico dell`acido montanico (cera E).<br \/>\n<strong>CATEGORIA FARMACOTERAPEUTICA:<\/strong><br \/>\nContraccettivo di tipo combinato per uso orale. Ogni compres-sa contiene due diversi ormoni femminili: gestodene ed etinilestradiolo. Poiche` tutte le compresse della confezione contengono la combinazione degli stessi ormoni nella stessa dose, ilprodotto e` considerato un contraccettivo orale monofasico di tipo combinato.<br \/>\n<strong>INDICAZIONI:<\/strong><br \/>\nPrevenzione del concepimento.<br \/>\n<strong>CONTROINDICAZIONI:<\/strong><br \/>\nI contraccettivi orali combinati non devono essere usati in presenza di unaqualunque delle seguenti condizioni: tromboflebite o disturbi tromboembolici; storia di tromboflebite venosa profonda o di disturbi tromboembolici; patologie arteriose cerebrovascolari o co-ronariche; sospetto o accertato carcinoma del seno; carcinoma dell`endometrio o altra accertata o sospetta neoplasia estrogeno-dipendente; sanguinamenti vaginali anomali di naturanon accertata; ittero colestatico gravidico o ittero associato ad un precedente utilizzo di contraccettivi orali combinati; adenomi o carcinomi epatici; gravidanza accertata o sospetta; iper-sensibilita` nei confronti di uno qualunque dei componenti di Minulet.<br \/>\n<strong>EFFETTI INDESIDERATI:<\/strong><br \/>\nEFFETTI LIEVI Talvolta, nei primi mesi di assunzione di Minulet possono verifi-carsi: cefalea; edema; nausea; vomito; crampi addominali; alterazione dell`appetito; aumento o diminuzione del peso corporeo; aggravamento della porfiria; depressione mentale; nervosismo;vertigini; modificazioni della libido; rash; eritema nodoso; acne; melasma che puo` essere persistente; irsutismo, alopecia ; intolleranza alle lenti a contatto; neurite ottica; emorragia da rot-tura; spotting; variazione del flusso mestruale; amenorrea; modifiche nell`estroversione e nella secrezione cervicale, vaginite, modifiche al seno, quali dolorabilita` al tatto, ingrossamento, se-crezione. E<br \/>\nFFETTI GRAVI Effetti piu` seri sono stati associati talvolta all`assunzione di contraccettiviorali. Trombosi (formazione di coaguli nei vasi sanguigni). Con i contraccettivi orali e` stata riscontrata un`incidenza leggermente piu` elevata nel rischio di trombosi. Le donne di eta` supe-riore ai 35 anni che mantengono l`abitudine al fumo in corso di trattamento con contraccettivi orali, sono piu` esposte ad attacchi cardiaci e ictus. E` importante smettere di fumare se si staassumendo un contraccettivo orale, come nel caso di Minulet. Inoltre, altri fattori di rischio, oltre al fumo, come ad esempio disturbi della coagulazione pre-esistenti, pressione arteriosa elevata,aterosclerosi, diabete e sovrappeso possono aumentare il rischio di trombosi. I contraccettivi orali combinati devono essere usati con cautela nelle donne con fattori di rischio per malattiacardiovascolare. In rare occasioni, l`uso dei contraccettivi orali puo` causare malattie epatiche e colecistiche quali ittero e, molto raramente, si associa a qualche forma di tumore epatico.Quest`ultimo puo` provocare un`emorragia intraddominale con pericolo per la vita. In caso di seri disturbi nella regione addominale superiore che non regrediscano spontaneamente, consultareil medico. Se si sospetta di avere una qualsiasi reazione indesiderata grave con l`uso di Minulet, sospendere l`assunzione delle compresse e consultare il medico al piu` presto.<br \/>\n<strong>PRECAUZIONI D`IMPIEGO:<\/strong><br \/>\nPrima di iniziare l`assunzione di un contraccettivo orale combinato de-vono essere effettuati una completa anamnesi medica personale e familiare ed un esame fisico,<br \/>\nche andrebbero ripetuti periodicamente durante il trattamento. L`esame fisico dovrebbe riguar-dare in modo particolare la pressione sanguigna, le ghiandole mammarie, l`addome, gli organi pelvici; dovrebbero, inoltre, essere eseguiti l`esame citologico della cervice ed i test di labora-torio fondamentali. S<br \/>\nITUAZIONI CHE IMPONGONO L`IMMEDIATA INTERRUZIONE DEL TRATTAMENTO Se siverifica una qualsiasi delle condizioni riportate di seguito, e` necessario interrompere l`assunzione di Minulet e consultare il proprio medico: Episodi di emicrania che non si verificavano primao che si verificano piu` intensamente rispetto a prima. Cefalea inconsuetamente ricorrente, persistente o di grave entita`. Improvvisi disturbi della vista, quali una non spiegabile parziale ocompleta perdita della vista o la diplopia(doppia immagine). In caso di comparsa di altri sintomi di formazione di coaguli ematici o sintomi di infiammazione venosa associata a formazione dicoaguli (tromboflebite), quali dolori insoliti alle gambe o gonfiore anomalo delle braccia o delle gambe. Dolori acuti al petto o respiro corto. Sensazione dolorosa di schiacciamento o di op-pressione al torace. 4 settimane prima di un intervento chirurgico, sino 2 settimane dopo di esso, e durante e dopo una prolungata immobilizzazione come in caso di costrizione a letto dopoun incidente o un`operazione o in caso di immobilizzazione, per es. dopo ingessatura di una gamba fratturata. Comparsa di ittero o di prurito in tutto il corpo. Aumento della frequenza diattacchi epilettici. Aumento significativo della pressione arteriosa. Insorgenza di grave depressione. Forti dolori nella parte alta dell`addome o inconsueto gonfiore addominale. Gravidanza.Comparsa di ipofolatemia (se la donna intende iniziare una gravidanza subito dopo l`interruzione del contraccettivo). PRECAUZIONI DA PRENDERE IN CASO DI MALATTIE PRE-ESISTENTI Talvolta le donneche soffrono gia` di una malattia o che sono in cura da un medico possono lo stesso assumere Minulet a condizione che si sottopongano a controlli medici piu` frequenti. E` necessario che ilmedico venga informato della presenza delle seguenti condizioni: Diabete. Iperlipidemia. Disfunzioni epatiche acute o croniche. Pressione arteriosa elevata. Vene varicose. Pregressa in-fiammazione delle vene (flebite). Epilessia. Disturbo del metabolismo noto come Porfiria. Disturbi motori (movimenti a scatti o difficolta` nel controllo dei muscoli). Disturbi renali. Malat-tie trombotiche, attacchi cardiaci, ictus in un membro della propria famiglia. Soprappeso. Cisti mammarie pregresse o precedenti familiari di cancro mammario. Grave depressione pregres-sa. Fibromi uterini. Emicrania. Situazioni che possono essere aggravate dalla ritenzione idrica. Ipercolesterolemia. Come tutti i contraccettivi orali, Minulet non protegge nei confronti dell`infe-zione da HIV (AIDS) e da altre malattie trasmesse sessualmente.<br \/>\n<strong>AVVERTENZE:<\/strong><br \/>\nNel caso di sanguinamento vaginale anormale, persistente o ricorrente di natura nonaccertata, devono essere prese appropriate misure diagnostiche per escludere la presenza di patologie maligne. In alcune donne, l`emorragia da sospensione potrebbe non presentarsi du-rante l`intervallo libero da compressa. Se il contraccettivo orale combinato non e` stato assunto regolarmente durante il ciclo che precede la prima mestruazione mancante o se si ha assenza di mestruazioni per due cicli successivi, deve essere esclusa la possibilita` che si sia instauratauna gravidanza. I pazienti trattati con contraccettivi orali non dovrebbero assumere preparazioni<br \/>\na base di hypericum perforatum, in quanto l`assunzione contemporanea di preparazioni a base di hypericum perforatum puo` causare perdita dell`efficacia anticoncezionale.<br \/>\n<strong>USO IN GRAVIDANZA:<\/strong><br \/>\nIl prodotto e` controindicato in gravidanza. Minulet puo` influenzare l`allattamen-to al seno. I contraccettivi orali combinati possono ridurre la quantita` e modificare la composizione del latte materno, pertanto il loro uso e` sconsigliato fino al termine dell`allattamento.Piccole quantita` di steroidi contraccettivi e\/o dei loro metaboliti sono state identificate nel latte materno, e sono stati riportati alcuni effetti collaterali sul bambino, incluso ittero e ingrossamen-to del seno. Consultare il proprio medico o il farmacista se si necessita di chiarimenti.<br \/>\n<strong>INTERAZIONI:<\/strong><br \/>\nE` importante informare il medico prima della prescrizione di Minulet di tutti i me-dicinali che si stanno assumendo, ed e` altresi` importante informare il medico o il dentista del fatto che si assume Minulet all`atto della prescrizione di nuovi farmaci. Alcuni medicinali possono diminuire l`efficacia del prodotto, quali gli antibiotici (come l`ampicillina e la rifampicina,letetracicline); la griseofulvina (usata per trattare le infezioni fungine); il fenilbutazone (usato come antinfiammatorio per trattare alcuni tipi di malattie delle articolazioni); la difenilidantoina,il fenobarbital, ed alcuni altri farmaci usati in pazienti epilettici; la carbamazepina (usata per trattare l`epilessia e altri tipi di malattie), il topiramato e alcuni inibitori della proteasi. Se si sta as-sumendo o si deve iniziare a prendere uno di questi farmaci, si potra` ugualmente usare Minulet ma sara` necessario adottare un altro metodo contraccettivo per tutto il periodo di assunzionedel farmaco stesso e per altri 7 giorni dopo averlo sospeso. Se questi 7 giorni oltrepassano la fine della confezione, la confezione successiva deve essere iniziata immediatamente senza al-cun intervallo di interruzione. In tal caso il flusso mestruale si presentera` soltanto alla fine della seconda confezione. Se il flusso mestruale non dovesse presentarsi durante l`intervallo di so-spensione delle compresse alla fine della seconda confezione, sara` necessario escludere una gravidanza prima di iniziare un nuovo ciclo di trattamento. Nel caso della rifampicina, sara` ne-cessario usare un altro metodo contraccettivo per tutto il periodo dell`assunzione e per 4 settimane dopo la sospensione del farmaco. Si possono anche verificare interazioni con farmaciinibitori degli enzimi microsomiali che potrebbero aumentare le concentrazioni di etinilestradiolo (per es. indinavir, fluconazolo). L`etinilestradiolo puo` interferire con il metabolismo di altri far-maci inibendo gli enzimi microsomiali epatici o inducendo la coniugazione epatica del farmaco, in particolare la glucuronizzazione. Conseguentemente, le concentrazioni plasmatiche e tessu-tali possono risultare aumentate o diminuite, rispettivamente (per es. ciclosporina, teofillina). Farmaci che agiscono come inibitori competitivi della solfatazione nella parete gastrointestinalepossono aumentare la biodisponibilita` dell`etinilestradiolo (per es. acido ascorbico). Nel caso dei pazienti diabetici, il fabbisogno del farmaco antidiabetico puo` subire variazioni. I pazientitrattati con contraccettivi orali non dovrebbero assumere preparazioni a base di hypericum perforatum, in quanto l`assunzione contemporanea di preparazioni a base di hypericum perforatumpuo` causare perdita dell`efficacia anticoncezionale. E<br \/>\nSAMI DI LABORATORIO L`uso degli steroidicontraccettivi puo` influenzare i risultati di alcuni esami di laboratorio, compresi i parametri biochimici della funzionalita` epatica, tiroidea, renale e surrenale; i livelli plasmatici delle proteine ditrasporto (per es. globulina legante i corticosteroidi e frazioni lipidiche\/lipoproteiche); i parametri del metabolismo dei carboidrati, della coagulazione e della fibrinolisi.<br \/>\n<strong>POSOLOGIA:<\/strong><br \/>\nLa confezione contiene 21 compresse. Deve essere presa una compressa al giornoper 21 giorni consecutivi. La prima compressa va estratta dalla casella della confezione calendario contrassegnata dal numero 1 (che si trova accanto alla parola &#8220;INIZIO&#8221;). La compressasuccessiva va prelevata il giorno dopo dalla casella vicina, seguendo la numerazione e la direzione delle frecce. Gratta l`indicatore posto accanto al giorno della settimana in cui hai preso laprima compressa. Questo stesso giorno della settimana rappresentera` il giorno di inizio di ogni successiva confezione; inoltre, esso rappresentera` lo stesso giorno della settimana in cui ver-ranno assunte le compresse 1, 8 e 15 (queste compresse hanno un margine colorato in giallo). Questo ti aiutera` a controllare e ad essere sicura che stai prendendo le compresse correttamen-te. Le compresse vanno ingerite senza masticare, con regolarita`, possibilmente sempre alla stessa ora, preferibilmente dopo il pasto serale. C ICLI SUCCESSIVI Dopo aver preso tutte le 21compresse, sospendere l`assunzione per 7 giorni. Durante questi 7 giorni si presentera` un`emorragia, di solito 2-3 giorni dopo l`assunzione dell`ultima compressa. Iniziare la successi-va confezione di Minulet l`8-o giorno, anche se l`emorragia e` ancora in corso. Questo significa che la seconda confezione di Minulet verra` iniziata esattamente nello stesso giorno della setti-mana in cui era stata iniziata la prima confezione, quattro settimane prima. C<br \/>\nOME INIZIARE IL TRATTAMENTO CON MINULET Nessun trattamento contraccettivo ormonale nel mese precedente.L`assunzione delle compresse deve iniziare il 1-o giorno del ciclo naturale della donna (cioe` il<br \/>\nprimo giorno dell`emorragia mestruale). E` possibile iniziare anche tra il 2-o e 7-o giorno del ciclo,ma durante il primo ciclo si raccomanda di impiegare anche un metodo contraccettivo non ormonale di barriera (come profilattici e spermicidi) per i primi 7 giorni d`assunzione delle com-presse. Passaggio da un altro contraccettivo orale combinato La prima compressa di Minulet deve essere assunta preferibilmente il giorno dopo l`ultima compressa attiva del precedentecontraccettivo, o al piu` tardi, il giorno dopo il consueto intervallo libero da compressa o il giorno dopo l`ultima compressa di placebo del precedente contraccettivo orale combinato. Passaggioda un contraccettivo a base di solo progestinico (minipillola, iniezione, impianto) E` possibile cambiare in qualunque momento se si proviene dalla minipillola, e l`assunzione di Minulet devecominciare il giorno successivo. Nel caso di un impianto l`assunzione di Minulet deve cominciare nello stesso giorno nel quale l`impianto viene rimosso o, nel caso di un iniettabile, nel gior-no in cui dovrebbe essere praticata la successiva iniezione. In tutti questi casi, la donna deve essere avvertita di usare anche un metodo contraccettivo non ormonale per i primi sette giornid`assunzione delle compresse. Dopo un aborto al primo trimestre E` possibile iniziare Minulet immediatamente. Non sono necessarie ulteriori misure contraccettive. Dopo un parto o unaborto al secondo trimestre Poiche` il periodo immediatamente successivo al parto e` associato ad un aumentato rischio di tromboembolismo, l`assunzione di contraccettivi orali combinati nondeve cominciare prima del 28-o giorno dopo il parto o dopo un aborto al secondo trimestre. Si deve raccomandare di usare anche un metodo contraccettivo non ormonale nei primi sette gior-ni d`assunzione delle compresse. Tuttavia, se nel frattempo, si fossero avuti rapporti sessuali, prima di iniziare effettivamente l`assunzione del contraccettivo orale combinato, si deve esclu-dere una gravidanza o si deve attendere la comparsa della prima mestruazione. R<br \/>\nACCOMANDAZIONI IN CASO DI VOMITO Se entro 3-4 ore dall`assunzione della compressa si verifica vomito,l`assorbimento puo` non essere completo. Se la donna non vuole modificare il consueto schema<br \/>\nposologico, deve prendere una o piu` compresse extra da una nuova confezione. P RECAUZIONI CONTRACCETTIVE SUPPLEMENTARI Nei casi in cui e` necessario usare altri metodi contraccettivi, oc-corre: usare un diaframma con spermicida o un profilattico; oppure evitare rapporti sessuali<br \/>\nNon usare metodi basati sul conteggio dei giorni o sul controllo della temperatura basale. Que-sto perche` i contraccettivi orali alterano le variazioni che si verificano normalmente nel ciclo mestruale, come per esempio le variazioni della temperatura e del muco cervicale.<br \/>\n<strong>OMISSIONE DI UNA O PIU` DOSI:<\/strong><br \/>\nSe si dimentica di assumere le compresse e soprattutto se le compres-se dimenticate prolungano l`intervallo libero da compressa, la protezione contraccettiva puo` risultare ridotta. Se sono state dimenticate delle compresse e si sono avuti rapporti sessuali lasettimana precedente la dimenticanza, e` necessario considerare la possibilita` che si sia instaurata una gravidanza. Se e` stata dimenticata una compressa e sono trascorse meno di 12 ore,questa deve essere presa non appena ci si accorge della dimenticanza. Le compresse successive devono essere assunte all`ora consueta. Se e` stata dimenticata una compressa e sono tra-scorse piu` di 12 ore o se sono state dimenticate piu` compresse, la protezione contraccettiva potrebbe essere ridotta. L`ultima compressa dimenticata deve essere assunta non appena ci siaccorge della dimenticanza, anche se questo significa assumere 2 compresse in un giorno. Le compresse successive devono essere assunte all`ora consueta. Inoltre un metodo contraccettivo non ormonale deve essere utilizzato per i successivi 7 giorni. Se questi 7 giorni oltrepas-sano l`ultima compressa della confezione che si sta utilizzando, la confezione successiva deve<br \/>\nessere iniziata non appena quella in uso e` terminata; non ci deve essere interruzione tra le dueconfezioni. Questo evita un`interruzione prolungata dell`assunzione delle compresse, che potrebbe aumentare il rischio che si verifichi un`ovulazione. E` improbabile che si verifichi un`emorragia da sospensione fino al termine della seconda confezione, potrebbe pero` verificarsispotting o emorragia da rottura nei giorni di assunzione delle compresse. Se al termine della seconda confezione non si verificasse un`emorragia, prima di riassumere una compressa dallaconfezione successiva, deve essere escluso che si sia instaurata una gravidanza.<br \/>\n<strong>SOVRADOSAGGIO:<\/strong><br \/>\nNon sono stati riportati gravi effetti tossici a seguito di ingestione di grosse quan-tita` di contraccettivi orali combinati da parte dei bambini. Il sovradosaggio puo` causare nausea e, nelle donne, emorragia da privazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutte le informazioni sulla Pillola Contraccettiva Minulet<\/p>\n","protected":false},"author":3,"featured_media":1014678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-1000061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contraccezione"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/posts\/1000061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/comments?post=1000061"}],"version-history":[{"count":0,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/posts\/1000061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/media\/1014678"}],"wp:attachment":[{"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/media?parent=1000061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/categories?post=1000061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comodo.it\/blog\/wp-json\/wp\/v2\/tags?post=1000061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}